{"id":29615,"date":"2020-01-26T12:01:06","date_gmt":"2020-01-26T11:01:06","guid":{"rendered":"https:\/\/cooksringroad.com\/?page_id=29615"},"modified":"2020-04-17T12:52:38","modified_gmt":"2020-04-17T10:52:38","slug":"datenschutz-und-impressum","status":"publish","type":"page","link":"https:\/\/cooksringroad.com\/de\/datenschutz-und-impressum\/","title":{"rendered":"DATENSCHUTZ UND IMPRESSUM"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; fullwidth=&#8220;on&#8220; _builder_version=&#8220;4.1&#8243;][et_pb_fullwidth_slider _builder_version=&#8220;4.3.4&#8243;][et_pb_slide heading=&#8220;Datenschutz und Impressum&#8220; _builder_version=&#8220;4.3.4&#8243; background_image=&#8220;https:\/\/cooksringroad.com\/wp-content\/uploads\/2020\/01\/20140518_190147-scaled.jpg&#8220; background_enable_image=&#8220;on&#8220;]<\/p>\n<p style=\"text-align: center;\">Dieser Blog verfolgt keinerlei kommerzielle Zwecke<\/p>\n<p>[\/et_pb_slide][\/et_pb_fullwidth_slider][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;3.22&#8243;][et_pb_row _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.3.4&#8243;]<\/p>\n<p>Cook&#8217;s Ring Road ist ein rein privater und nicht-kommerzieller Blog. Wir bieten Informationen \u00fcber Roadtrips in und Rezepte aus verschiedenen Regionen an und tun dies gerne auf Anfrage und kostenlos.<\/p>\n<p>Trotzdem und nur um sicher zu gehen, findest du unten Informationen zu rechtlichen Aspekten, obwohl dies wahrscheinlich gar nicht n\u00f6tig ist.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_divider color=&#8220;#000000&#8243; _builder_version=&#8220;3.19.1&#8243; height=&#8220;5px&#8220;][\/et_pb_divider][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<h2>Datenschutz<\/h2>\n<h4><strong>\u00dcbersicht der Verarbeitungen<\/strong><\/h4>\n<p>Die nachfolgende \u00dcbersicht fasst die Arten der verarbeiteten Daten und die Zwecke ihrer Verarbeitung zusammen und verweist auf die betroffenen Personen.<\/p>\n<p><strong>Arten der verarbeiteten Daten: <\/strong>Bestandsdaten (z.B. Namen, Adressen); Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos); Kontaktdaten (z.B. E-Mail, Telefonnummern); Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen); Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten)<\/p>\n<p><strong>Kategorien betroffener Personen: <\/strong>Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten)<\/p>\n<p><strong>Zwecke der Verarbeitung: <\/strong>Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit; Feedback (z.B. Sammeln von Feedback via Online-Formular); Kontaktanfragen und Kommunikation; Remarketing; Reichweitenmessung (z.B. Zugriffsstatistiken, Erkennung wiederkehrender Besucher); Sicherheitsma\u00dfnahmen; Tracking (z.B. interessens-\/verhaltensbezogenes Profiling, Nutzung von Cookies); Vertragliche Leistungen und Service; Verwaltung und Beantwortung von Anfragen<\/p>\n<p><strong>Ma\u00dfgebliche Rechtsgrundlagen: <\/strong>Im Folgenden teilen wir die Rechtsgrundlagen der Datenschutzgrundverordnung (DSGVO), auf deren Basis wir die personenbezogenen Daten verarbeiten, mit. Bitte beachten Sie, dass zus\u00e4tzlich zu den Regelungen der DSGVO die nationalen Datenschutzvorgaben in Ihrem bzw. unserem Wohn- und Sitzland gelten k\u00f6nnen. Sollten ferner im Einzelfall speziellere Rechtsgrundlagen ma\u00dfgeblich sein, teilen wir Ihnen diese in der Datenschutzerkl\u00e4rung mit.<\/p>\n<ul>\n<li><strong>Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO)<\/strong> &#8211; Die betroffene Person hat ihre Einwilligung in die Verarbeitung der sie betreffenden personenbezogenen Daten f\u00fcr einen spezifischen Zweck oder mehrere bestimmte Zwecke gegeben.<\/li>\n<li><strong>Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO)<\/strong> &#8211; Die Verarbeitung ist f\u00fcr die Erf\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich, die auf Anfrage der betroffenen Person erfolgen.<\/li>\n<li><strong>Schutz lebenswichtiger Interessen (Art. 6 Abs. 1 S. 1 lit. d. DSGVO)<\/strong> &#8211; Die Verarbeitung ist erforderlich, um lebenswichtige Interessen der betroffenen Person oder einer anderen nat\u00fcrlichen Person zu sch\u00fctzen.<\/li>\n<li><strong>Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO)<\/strong> &#8211; Die Verarbeitung ist zur Wahrung der berechtigten Interessen des Verantwortlichen oder eines Dritten erforderlich, sofern nicht die Interessen oder Grundrechte und Grundfreiheiten der betroffenen Person, die den Schutz personenbezogener Daten erfordern, \u00fcberwiegen.<\/li>\n<\/ul>\n<p><strong>Nationale Datenschutzregelungen in der Schweiz<\/strong>: Zus\u00e4tzlich zu den Datenschutzregelungen der Datenschutz-Grundverordnung gelten nationale Regelungen zum Datenschutz in der Schweiz. Hierzu geh\u00f6rt insbesondere das Bundesgesetz zum Datenschutz (DSG). Das DSG gilt insbesondere dann, wenn keine EU\/EWG-B\u00fcrger betroffen sind und z.B. nur Daten von Schweizer B\u00fcrgern verarbeitet werden.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<h4><strong>Sicherheitsma\u00dfnahmen<\/strong><\/h4>\n<p>Wir treffen nach Ma\u00dfgabe der gesetzlichen Vorgaben unter Ber\u00fccksichtigung des Stands der Technik, der Implementierungskosten und der Art, des Umfangs, der Umst\u00e4nde und der Zwecke der Verarbeitung sowie der unterschiedlichen Eintrittswahrscheinlichkeiten und des Ausma\u00dfes der Bedrohung der Rechte und Freiheiten nat\u00fcrlicher Personen geeignete technische und organisatorische Ma\u00dfnahmen, um ein dem Risiko angemessenes Schutzniveau zu gew\u00e4hrleisten. Zu den Ma\u00dfnahmen geh\u00f6ren insbesondere die Sicherung der Vertraulichkeit, Integrit\u00e4t und Verf\u00fcgbarkeit von Daten durch Kontrolle des physischen und elektronischen Zugangs zu den Daten als auch des sie betreffenden Zugriffs, der Eingabe, der Weitergabe, der Sicherung der Verf\u00fcgbarkeit und ihrer Trennung. Des Weiteren haben wir Verfahren eingerichtet, die eine Wahrnehmung von Betroffenenrechten, die L\u00f6schung von Daten und Reaktionen auf die Gef\u00e4hrdung der Daten gew\u00e4hrleisten. Ferner ber\u00fccksichtigen wir den Schutz personenbezogener Daten bereits bei der Entwicklung bzw. Auswahl von Hardware, Software sowie Verfahren entsprechend dem Prinzip des Datenschutzes, durch Technikgestaltung und durch datenschutzfreundliche Voreinstellungen.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<p><strong>\u00dcbermittlung und Offenbarung von personenbezogenen Daten<\/strong><\/p>\n<p>Im Rahmen unserer Verarbeitung von personenbezogenen Daten kommt es vor, dass die Daten an andere Stellen, Unternehmen, rechtlich selbstst\u00e4ndige Organisationseinheiten oder Personen \u00fcbermittelt oder sie ihnen gegen\u00fcber offengelegt werden. Zu den Empf\u00e4ngern dieser Daten k\u00f6nnen z.B. Zahlungsinstitute im Rahmen von Zahlungsvorg\u00e4ngen, mit IT-Aufgaben beauftragte Dienstleister oder Anbieter von Diensten und Inhalten, die in eine Webseite eingebunden werden, geh\u00f6ren. In solchen Fall beachten wir die gesetzlichen Vorgaben und schlie\u00dfen insbesondere entsprechende Vertr\u00e4ge bzw. Vereinbarungen, die dem Schutz Ihrer Daten dienen, mit den Empf\u00e4ngern Ihrer Daten ab.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<p><strong>Datenverarbeitung in Drittl\u00e4ndern<\/strong><\/p>\n<p>Sofern wir Daten in einem Drittland (d.h., au\u00dferhalb der Europ\u00e4ischen Union (EU), des Europ\u00e4ischen Wirtschaftsraums (EWR)) verarbeiten oder die Verarbeitung im Rahmen der Inanspruchnahme von Diensten Dritter oder der Offenlegung bzw. \u00dcbermittlung von Daten an andere Personen, Stellen oder Unternehmen stattfindet, erfolgt dies nur im Einklang mit den gesetzlichen Vorgaben.<\/p>\n<p>Vorbehaltlich ausdr\u00fccklicher Einwilligung oder vertraglich oder gesetzlich erforderlicher \u00dcbermittlung verarbeiten oder lassen wir die Daten nur in Drittl\u00e4ndern mit einem anerkannten Datenschutzniveau, zu denen die unter dem &#8222;Privacy-Shield&#8220; zertifizierten US-Verarbeiter geh\u00f6ren, oder auf Grundlage besonderer Garantien, wie z.B. vertraglicher Verpflichtung durch sogenannte Standardschutzklauseln der EU-Kommission, des Vorliegens von Zertifizierungen oder verbindlicher interner Datenschutzvorschriften, verarbeiten (Art. 44 bis 49 DSGVO, Informationsseite der EU-Kommission: <a href=\"https:\/\/ec.europa.eu\/info\/law\/law-topic\/data-protection\/international-dimension-data-protection_de\">https:\/\/ec.europa.eu\/info\/law\/law-topic\/data-protection\/international-dimension-data-protection_de<\/a>).<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<p><strong>Einsatz von Cookies<\/strong><\/p>\n<p>Cookies sind Textdateien, die Daten von besuchten Websites oder Domains enthalten und von einem Browser auf dem Computer des Benutzers gespeichert werden. Ein Cookie dient in erster Linie dazu, die Informationen \u00fcber einen Benutzer w\u00e4hrend oder nach seinem Besuch innerhalb eines Onlineangebotes zu speichern. Zu den gespeicherten Angaben k\u00f6nnen z.B. die Spracheinstellungen auf einer Webseite, der Loginstatus, ein Warenkorb oder die Stelle, an der ein Video geschaut wurde, geh\u00f6ren. Zu dem Begriff der Cookies z\u00e4hlen wir ferner andere Technologien, die die gleichen Funktionen wie Cookies erf\u00fcllen (z.B., wenn Angaben der Nutzer anhand pseudonymer Onlinekennzeichnungen gespeichert werden, auch als &#8222;Nutzer-IDs&#8220; bezeichnet).<\/p>\n<p><strong>Die folgenden Cookie-Typen und Funktionen werden unterschieden:<\/strong><\/p>\n<ul>\n<li><strong>Tempor\u00e4re Cookies (auch: Session- oder Sitzungs-Cookies):<\/strong>\u00a0Tempor\u00e4re Cookies werden sp\u00e4testens gel\u00f6scht, nachdem ein Nutzer ein Online-Angebot verlassen und seinen Browser geschlossen hat.<\/li>\n<li><strong>Permanente Cookies:<\/strong>\u00a0Permanente Cookies bleiben auch nach dem Schlie\u00dfen des Browsers gespeichert. So kann beispielsweise der Login-Status gespeichert oder bevorzugte Inhalte direkt angezeigt werden, wenn der Nutzer eine Website erneut besucht. Ebenso k\u00f6nnen die Interessen von Nutzern, die zur Reichweitenmessung oder zu Marketingzwecken verwendet werden, in einem solchen Cookie gespeichert werden.<\/li>\n<li><strong>First-Party-Cookies:<\/strong>\u00a0First-Party-Cookies werden von uns selbst gesetzt.<\/li>\n<li><strong>Third-Party-Cookies (auch: Drittanbieter-Cookies)<\/strong>: Drittanbieter-Cookies werden haupts\u00e4chlich von Werbetreibenden (sog. Dritten) verwendet, um Benutzerinformationen zu verarbeiten.<\/li>\n<li><strong>Notwendige (auch: essentielle oder unbedingt erforderliche) Cookies:<\/strong> Cookies k\u00f6nnen zum einen f\u00fcr den Betrieb einer Webseite unbedingt erforderlich sein (z.B. um Logins oder andere Nutzereingaben zu speichern oder aus Gr\u00fcnden der Sicherheit).<\/li>\n<li><strong>Statistik-, Marketing- und Personalisierungs-Cookies<\/strong>: Ferner werden Cookies im Regelfall auch im Rahmen der Reichweitenmessung eingesetzt sowie dann, wenn die Interessen eines Nutzers oder sein Verhalten (z.B. Betrachten bestimmter Inhalte, Nutzen von Funktionen etc.) auf einzelnen Webseiten in einem Nutzerprofil gespeichert werden. Solche Profile dienen dazu, den Nutzern z.B. Inhalte anzuzeigen, die ihren potentiellen Interessen entsprechen. Dieses Verfahren wird auch als &#8222;Tracking&#8220;, d.h., Nachverfolgung der potentiellen Interessen der Nutzer bezeichnet. Soweit wir Cookies oder &#8222;Tracking&#8220;-Technologien einsetzen, informieren wir Sie gesondert in unserer Datenschutzerkl\u00e4rung oder im Rahmen der Einholung einer Einwilligung.<\/li>\n<\/ul>\n<p><strong>Hinweise zu Rechtsgrundlagen: <\/strong>Auf welcher Rechtsgrundlage wir Ihre personenbezogenen Daten mit Hilfe von Cookies verarbeiten, h\u00e4ngt davon ab, ob wir Sie um eine Einwilligung bitten. Falls dies zutrifft und Sie in die Nutzung von Cookies einwilligen, ist die Rechtsgrundlage der Verarbeitung Ihrer Daten die erkl\u00e4rte Einwilligung. Andernfalls werden die mithilfe von Cookies verarbeiteten Daten auf Grundlage unserer berechtigten Interessen (z.B. an einem betriebswirtschaftlichen Betrieb unseres Onlineangebotes und dessen Verbesserung) verarbeitet oder, wenn der Einsatz von Cookies erforderlich ist, um unsere vertraglichen Verpflichtungen zu erf\u00fcllen.<\/p>\n<p><strong>Allgemeine Hinweise zum Widerruf und Widerspruch (Opt-Out): <\/strong>Abh\u00e4ngig davon, ob die Verarbeitung auf Grundlage einer Einwilligung oder gesetzlichen Erlaubnis erfolgt, haben Sie jederzeit die M\u00f6glichkeit, eine erteilte Einwilligung zu widerrufen oder der Verarbeitung Ihrer Daten durch Cookie-Technologien zu widersprechen (zusammenfassend als &#8222;Opt-Out&#8220; bezeichnet). Sie k\u00f6nnen Ihren Widerspruch zun\u00e4chst mittels der Einstellungen Ihres Browsers erkl\u00e4ren, z.B., indem Sie die Nutzung von Cookies deaktivieren (wobei hierdurch auch die Funktionsf\u00e4higkeit unseres Onlineangebotes eingeschr\u00e4nkt werden kann). Ein Widerspruch gegen den Einsatz von Cookies zu Zwecken des Onlinemarketings kann auch mittels einer Vielzahl von Diensten, vor allem im Fall des Trackings, \u00fcber die Webseiten <a href=\"https:\/\/optout.aboutads.info\">https:\/\/optout.aboutads.info<\/a> und <a href=\"https:\/\/www.youronlinechoices.com\/\">https:\/\/www.youronlinechoices.com\/<\/a> erkl\u00e4rt werden. Daneben k\u00f6nnen Sie weitere Widerspruchshinweise im Rahmen der Angaben zu den eingesetzten Dienstleistern und Cookies erhalten.<\/p>\n<p><strong>Verarbeitung von Cookie-Daten auf Grundlage einer Einwilligung<\/strong>: Bevor wir Daten im Rahmen der Nutzung von Cookies verarbeiten oder verarbeiten lassen, bitten wir die Nutzer um eine jederzeit widerrufbare Einwilligung. Bevor die Einwilligung nicht ausgesprochen wurde, werden allenfalls Cookies eingesetzt, die f\u00fcr den Betrieb unseres Onlineangebotes erforderlich sind. Deren Einsatz erfolgt auf der Grundlage unseres Interesses und des Interesses der Nutzer an der erwarteten Funktionsf\u00e4higkeit unseres Onlineangebotes.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<p><strong>Blogs und Publikationsmedien<\/strong><\/p>\n<p>Wir nutzen Blogs oder vergleichbare Mittel der Onlinekommunikation und Publikation (nachfolgend &#8222;Publikationsmedium&#8220;). Die Daten der Leser werden f\u00fcr die Zwecke des Publikationsmediums nur insoweit verarbeitet, als es f\u00fcr dessen Darstellung und die Kommunikation zwischen Autoren und Lesern oder aus Gr\u00fcnden der Sicherheit erforderlich ist. Im \u00dcbrigen verweisen wir auf die Informationen zur Verarbeitung der Besucher unseres Publikationsmediums im Rahmen dieser Datenschutzhinweise.<\/p>\n<p><strong>Kommentare und Beitr\u00e4ge<\/strong>: Wenn Nutzer Kommentare oder sonstige Beitr\u00e4ge hinterlassen, k\u00f6nnen ihre IP-Adressen auf Grundlage unserer berechtigten Interessen gespeichert werden. Das erfolgt zu unserer Sicherheit, falls jemand in Kommentaren und Beitr\u00e4gen widerrechtliche Inhalte hinterl\u00e4sst (Beleidigungen, verbotene politische Propaganda etc.). In diesem Fall k\u00f6nnen wir selbst f\u00fcr den Kommentar oder Beitrag belangt werden und sind daher an der Identit\u00e4t des Verfassers interessiert. Des Weiteren behalten wir uns vor, auf Grundlage unserer berechtigten Interessen die Angaben der Nutzer zwecks Spamerkennung zu verarbeiten. Auf derselben Rechtsgrundlage behalten wir uns vor, im Fall von Umfragen die IP-Adressen der Nutzer f\u00fcr deren Dauer zu speichern und Cookies zu verwenden, um Mehrfachabstimmungen zu vermeiden. Die im Rahmen der Kommentare und Beitr\u00e4ge mitgeteilten Informationen zur Person, etwaige Kontakt- sowie Webseiteninformationen als auch die inhaltlichen Angaben werden von uns bis zum Widerspruch der Nutzer dauerhaft gespeichert.<\/p>\n<p><strong>Kommentarabonnements<\/strong>: Die Nachfolgekommentare k\u00f6nnen von Nutzern mit deren Einwilligung abonniert werden. Die Nutzer erhalten eine Best\u00e4tigungsemail, um zu \u00fcberpr\u00fcfen, ob sie der Inhaber der eingegebenen Emailadresse sind. Nutzer k\u00f6nnen laufende Kommentarabonnements jederzeit abbestellen. Die Best\u00e4tigungsemail wird Hinweise zu den Widerrufsm\u00f6glichkeiten enthalten. F\u00fcr die Zwecke des Nachweises der Einwilligung der Nutzer speichern wir den Anmeldezeitpunkt nebst der IP-Adresse der Nutzer und l\u00f6schen diese Informationen, wenn Nutzer sich von dem Abonnement abmelden. Sie k\u00f6nnen den Empfang unseres Abonnements jederzeit k\u00fcndigen, d.h., Ihre Einwilligungen widerrufen. Wir k\u00f6nnen die ausgetragenen E-Mail-Adressen bis zu drei Jahren auf Grundlage unserer berechtigten Interessen speichern, bevor wir sie l\u00f6schen, um eine ehemals gegebene Einwilligung nachweisen zu k\u00f6nnen. Die Verarbeitung dieser Daten wird auf den Zweck einer m\u00f6glichen Abwehr von Anspr\u00fcchen beschr\u00e4nkt. Ein individueller L\u00f6schungsantrag ist jederzeit m\u00f6glich, sofern zugleich das ehemalige Bestehen einer Einwilligung best\u00e4tigt wird.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Vertragliche Leistungen und Service, Feedback (z.B. Sammeln von Feedback via Online-Formular), Sicherheitsma\u00dfnahmen, Verwaltung und Beantwortung von Anfragen, Kontaktanfragen und Kommunikation.<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO), Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO), Schutz lebenswichtiger Interessen (Art. 6 Abs. 1 S. 1 lit. d. DSGVO).<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<p><strong>Bereitstellung des Onlineangebotes und Webhosting<\/strong><\/p>\n<p>Um unser Onlineangebot sicher und effizient bereitstellen zu k\u00f6nnen, nehmen wir die Leistungen von einem oder mehreren Webhosting-Anbietern in Anspruch, von deren Servern (bzw. von ihnen verwalteten Servern) das Onlineangebot abgerufen werden kann. Zu diesen Zwecken k\u00f6nnen wir Infrastruktur- und Plattformdienstleistungen, Rechenkapazit\u00e4t, Speicherplatz und Datenbankdienste sowie Sicherheitsleistungen und technische Wartungsleistungen in Anspruch nehmen. Zu den im Rahmen der Bereitstellung des Hostingangebotes verarbeiteten Daten k\u00f6nnen alle die Nutzer unseres Onlineangebotes betreffenden Angaben geh\u00f6ren, die im Rahmen der Nutzung und der Kommunikation anfallen. Hierzu geh\u00f6ren regelm\u00e4\u00dfig die IP-Adresse, die notwendig ist, um die Inhalte von Onlineangeboten an Browser ausliefern zu k\u00f6nnen, und alle innerhalb unseres Onlineangebotes oder von Webseiten get\u00e4tigten Eingaben.<\/p>\n<p><strong>Erhebung von Zugriffsdaten und Logfiles<\/strong>: Wir selbst (bzw. unser Webhostinganbieter) erheben Daten zu jedem Zugriff auf den Server (sogenannte Serverlogfiles). Zu den Serverlogfiles k\u00f6nnen die Adresse und Name der abgerufenen Webseiten und Dateien, Datum und Uhrzeit des Abrufs, \u00fcbertragene Datenmengen, Meldung \u00fcber erfolgreichen Abruf, Browsertyp nebst Version, das Betriebssystem des Nutzers, Referrer URL (die zuvor besuchte Seite) und im Regelfall IP-Adressen und der anfragende Provider geh\u00f6ren. Die Serverlogfiles k\u00f6nnen zum einen zu Zwecken der Sicherheit eingesetzt werden, z.B., um eine \u00dcberlastung der Server zu vermeiden (insbesondere im Fall von missbr\u00e4uchlichen Angriffen, sogenannten DDoS-Attacken) und zum anderen, um die Auslastung der Server und ihre Stabilit\u00e4t sicherzustellen.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<p><strong>Pr\u00e4senzen in sozialen Netzwerken<\/strong><\/p>\n<p>Wir unterhalten Onlinepr\u00e4senzen innerhalb sozialer Netzwerke, um mit den dort aktiven Nutzern zu kommunizieren oder um dort Informationen \u00fcber uns anzubieten. Wir weisen darauf hin, dass dabei Daten der Nutzer au\u00dferhalb des Raumes der Europ\u00e4ischen Union verarbeitet werden k\u00f6nnen. Hierdurch k\u00f6nnen sich f\u00fcr die Nutzer Risiken ergeben, weil so z.B. die Durchsetzung der Rechte der Nutzer erschwert werden k\u00f6nnte. Im Hinblick auf US-Anbieter, die unter dem Privacy-Shield zertifiziert sind oder vergleichbare Garantien eines sicheren Datenschutzniveaus bieten, weisen wir darauf hin, dass sie sich damit verpflichten, die Datenschutzstandards der EU einzuhalten. Ferner werden die Daten der Nutzer innerhalb sozialer Netzwerke im Regelfall f\u00fcr Marktforschungs- und Werbezwecke verarbeitet. So k\u00f6nnen z.B. anhand des Nutzungsverhaltens und sich daraus ergebender Interessen der Nutzer Nutzungsprofile erstellt werden. Die Nutzungsprofile k\u00f6nnen wiederum verwendet werden, um z.B. Werbeanzeigen innerhalb und au\u00dferhalb der Netzwerke zu schalten, die mutma\u00dflich den Interessen der Nutzer entsprechen. Zu diesen Zwecken werden im Regelfall Cookies auf den Rechnern der Nutzer gespeichert, in denen das Nutzungsverhalten und die Interessen der Nutzer gespeichert werden. Ferner k\u00f6nnen in den Nutzungsprofilen auch Daten unabh\u00e4ngig der von den Nutzern verwendeten Ger\u00e4te gespeichert werden (insbesondere, wenn die Nutzer Mitglieder der jeweiligen Plattformen sind und bei diesen eingeloggt sind). F\u00fcr eine detaillierte Darstellung der jeweiligen Verarbeitungsformen und der Widerspruchsm\u00f6glichkeiten (Opt-Out) verweisen wir auf die Datenschutzerkl\u00e4rungen und Angaben der Betreiber der jeweiligen Netzwerke. Auch im Fall von Auskunftsanfragen und der Geltendmachung von Betroffenenrechten weisen wir darauf hin, dass diese am effektivsten bei den Anbietern geltend gemacht werden k\u00f6nnen. Nur die Anbieter haben jeweils Zugriff auf die Daten der Nutzer und k\u00f6nnen direkt entsprechende Ma\u00dfnahmen ergreifen und Ausk\u00fcnfte geben. Sollten Sie dennoch Hilfe ben\u00f6tigen, dann k\u00f6nnen Sie sich an uns wenden.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Kontaktanfragen und Kommunikation, Tracking (z.B. interessens-\/verhaltensbezogenes Profiling, Nutzung von Cookies), Remarketing, Reichweitenmessung (z.B. Zugriffsstatistiken, Erkennung wiederkehrender Besucher).<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/li>\n<\/ul>\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\/strong><\/p>\n<ul>\n<li><strong>Instagram :<\/strong> Soziales Netzwerk; Dienstanbieter: Instagram Inc., 1601 Willow Road, Menlo Park, CA, 94025, USA; Website: <a href=\"https:\/\/www.instagram.com\">https:\/\/www.instagram.com<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/instagram.com\/about\/legal\/privacy\">https:\/\/instagram.com\/about\/legal\/privacy<\/a>.<\/li>\n<li><strong>Facebook:<\/strong> Soziales Netzwerk; Dienstanbieter: Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland, Mutterunternehmen: Facebook, 1 Hacker Way, Menlo Park, CA 94025, USA; Website: <a href=\"https:\/\/www.facebook.com\">https:\/\/www.facebook.com<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/www.facebook.com\/about\/privacy\">https:\/\/www.facebook.com\/about\/privacy<\/a>; Privacy Shield (Gew\u00e4hrleistung Datenschutzniveau bei Verarbeitung von Daten in den USA): <a href=\"https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000GnywAAC&amp;status=Active\">https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000GnywAAC&amp;status=Active<\/a>; Widerspruchsm\u00f6glichkeit (Opt-Out): Einstellungen f\u00fcr Werbeanzeigen: <a href=\"https:\/\/www.facebook.com\/settings?tab=ads\">https:\/\/www.facebook.com\/settings?tab=ads<\/a>; Zus\u00e4tzliche Hinweise zum Datenschutz: Vereinbarung \u00fcber gemeinsame Verarbeitung personenbezogener Daten auf Facebook-Seiten: <a href=\"https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum\">https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum<\/a>, Datenschutzhinweise f\u00fcr Facebook-Seiten: <a href=\"https:\/\/www.facebook.com\/legal\/terms\/information_about_page_insights_data\">https:\/\/www.facebook.com\/legal\/terms\/information_about_page_insights_data<\/a>.<\/li>\n<li><strong>Pinterest:<\/strong> Soziales Netzwerk; Dienstanbieter: Pinterest Inc., 635 High Street, Palo Alto, CA, 94301, USA,; Website: <a href=\"https:\/\/www.pinterest.com\">https:\/\/www.pinterest.com<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/about.pinterest.com\/de\/privacy-policy\">https:\/\/about.pinterest.com\/de\/privacy-policy<\/a>; Widerspruchsm\u00f6glichkeit (Opt-Out): <a href=\"https:\/\/about.pinterest.com\/de\/privacy-policy\">https:\/\/about.pinterest.com\/de\/privacy-policy<\/a>.<\/li>\n<li><strong>Twitter:<\/strong> Soziales Netzwerk; Dienstanbieter: Twitter Inc., 1355 Market Street, Suite 900, San Francisco, CA 94103, USA; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/twitter.com\/de\/privacy\">https:\/\/twitter.com\/de\/privacy<\/a>, (Einstellungen) <a href=\"https:\/\/twitter.com\/personalization\">https:\/\/twitter.com\/personalization<\/a>; Privacy Shield (Gew\u00e4hrleistung Datenschutzniveau bei Verarbeitung von Daten in den USA): <a href=\"https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000TORzAAO&amp;status=Active\">https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000TORzAAO&amp;status=Active<\/a>.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<p><strong>Plugins und eingebettete Funktionen sowie Inhalte<\/strong><\/p>\n<p>Wir binden in unser Onlineangebot Funktions- und Inhaltselemente ein, die von den Servern ihrer jeweiligen Anbieter (nachfolgend bezeichnet als &#8222;Drittanbieter\u201d) bezogen werden. Dabei kann es sich zum Beispiel um Grafiken, Videos oder Social-Media-Schaltfl\u00e4chen sowie Beitr\u00e4ge handeln (nachfolgend einheitlich bezeichnet als &#8222;Inhalte\u201d). Die Einbindung setzt immer voraus, dass die Drittanbieter dieser Inhalte die IP-Adresse der Nutzer verarbeiten, da sie ohne die IP-Adresse die Inhalte nicht an deren Browser senden k\u00f6nnten. Die IP-Adresse ist damit f\u00fcr die Darstellung dieser Inhalte oder Funktionen erforderlich. Wir bem\u00fchen uns, nur solche Inhalte zu verwenden, deren jeweilige Anbieter die IP-Adresse lediglich zur Auslieferung der Inhalte verwenden. Drittanbieter k\u00f6nnen ferner sogenannte Pixel-Tags (unsichtbare Grafiken, auch als &#8222;Web Beacons&#8220; bezeichnet) f\u00fcr statistische oder Marketingzwecke verwenden. Durch die &#8222;Pixel-Tags&#8220; k\u00f6nnen Informationen, wie der Besucherverkehr auf den Seiten dieser Webseite, ausgewertet werden. Die pseudonymen Informationen k\u00f6nnen ferner in Cookies auf dem Ger\u00e4t der Nutzer gespeichert werden und unter anderem technische Informationen zum Browser und zum Betriebssystem, zu verweisenden Webseiten, zur Besuchszeit sowie weitere Angaben zur Nutzung unseres Onlineangebotes enthalten als auch mit solchen Informationen aus anderen Quellen verbunden werden.<\/p>\n<p><strong>Hinweise zu Rechtsgrundlagen:<\/strong> Sofern wir die Nutzer um deren Einwilligung in den Einsatz der Drittanbieter bitten, ist die Rechtsgrundlage der Verarbeitung von Daten die Einwilligung. Ansonsten werden die Daten der Nutzer auf Grundlage unserer berechtigten Interessen (d.h. Interesse an effizienten, wirtschaftlichen und empf\u00e4ngerfreundlichen Leistungen) verarbeitet. In diesem Zusammenhang m\u00f6chten wir Sie auch auf die Informationen zur Verwendung von Cookies in dieser Datenschutzerkl\u00e4rung hinweisen.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<p><strong>L\u00f6schung von Daten<\/strong><\/p>\n<p>Die von uns verarbeiteten Daten werden nach Ma\u00dfgabe der gesetzlichen Vorgaben gel\u00f6scht, sobald deren zur Verarbeitung erlaubten Einwilligungen widerrufen werden oder sonstige Erlaubnisse entfallen (z.B., wenn der Zweck der Verarbeitung dieser Daten entfallen ist oder sie f\u00fcr den Zweck nicht erforderlich sind). Sofern die Daten nicht gel\u00f6scht werden, weil sie f\u00fcr andere und gesetzlich zul\u00e4ssige Zwecke erforderlich sind, wird deren Verarbeitung auf diese Zwecke beschr\u00e4nkt. D.h., die Daten werden gesperrt und nicht f\u00fcr andere Zwecke verarbeitet. Das gilt z.B. f\u00fcr Daten, die aus handels- oder steuerrechtlichen Gr\u00fcnden aufbewahrt werden m\u00fcssen oder deren Speicherung zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder juristischen Person erforderlich ist. Weitere Hinweise zu der L\u00f6schung von personenbezogenen Daten k\u00f6nnen ferner im Rahmen der einzelnen Datenschutzhinweise dieser Datenschutzerkl\u00e4rung erfolgen.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<p><strong>\u00c4nderung und Aktualisierung der Datenschutzerkl\u00e4rung<\/strong><\/p>\n<p>Wir bitten Sie, sich regelm\u00e4\u00dfig \u00fcber den Inhalt unserer Datenschutzerkl\u00e4rung zu informieren. Wir passen die Datenschutzerkl\u00e4rung an, sobald die \u00c4nderungen der von uns durchgef\u00fchrten Datenverarbeitungen dies erforderlich machen. Wir informieren Sie, sobald durch die \u00c4nderungen eine Mitwirkungshandlung Ihrerseits (z.B. Einwilligung) oder eine sonstige individuelle Benachrichtigung erforderlich wird. Sofern wir in dieser Datenschutzerkl\u00e4rung Adressen und Kontaktinformationen von Unternehmen und Organisationen angeben, bitten wir zu beachten, dass die Adressen sich \u00fcber die Zeit \u00e4ndern k\u00f6nnen und bitten die Angaben vor Kontaktaufnahme zu pr\u00fcfen.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<p><strong>Rechte der betroffenen Personen<\/strong><\/p>\n<p>Ihnen stehen als Betroffene nach der DSGVO verschiedene Rechte zu, die sich insbesondere aus Art. 15 bis 18 und 21 DSGVO ergeben:<\/p>\n<ul>\n<li><strong>Widerspruchsrecht: <\/strong>Sie haben das Recht, aus Gr\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten, die aufgrund von Art. 6 Abs. 1 lit. e oder f DSGVO erfolgt, Widerspruch einzulegen; dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling. Werden die Sie betreffenden personenbezogenen Daten verarbeitet, um Direktwerbung zu betreiben, haben Sie das Recht, jederzeit Widerspruch gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen; dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht.<\/li>\n<li><strong>Widerrufsrecht bei Einwilligungen:<\/strong> Sie haben das Recht, erteilte Einwilligungen jederzeit zu widerrufen.<\/li>\n<li><strong>Auskunftsrecht:<\/strong> Sie haben das Recht, eine Best\u00e4tigung dar\u00fcber zu verlangen, ob betreffende Daten verarbeitet werden und auf Auskunft \u00fcber diese Daten sowie auf weitere Informationen und Kopie der Daten entsprechend den gesetzlichen Vorgaben.<\/li>\n<li><strong>Recht auf Berichtigung:<\/strong> Sie haben entsprechend den gesetzlichen Vorgaben das Recht, die Vervollst\u00e4ndigung der Sie betreffenden Daten oder die Berichtigung der Sie betreffenden unrichtigen Daten zu verlangen.<\/li>\n<li><strong>Recht auf L\u00f6schung und Einschr\u00e4nkung der Verarbeitung:<\/strong> Sie haben nach Ma\u00dfgabe der gesetzlichen Vorgaben das Recht, zu verlangen, dass Sie betreffende Daten unverz\u00fcglich gel\u00f6scht werden, bzw. alternativ nach Ma\u00dfgabe der gesetzlichen Vorgaben eine Einschr\u00e4nkung der Verarbeitung der Daten zu verlangen.<\/li>\n<li><strong>Recht auf Daten\u00fcbertragbarkeit:<\/strong> Sie haben das Recht, Sie betreffende Daten, die Sie uns bereitgestellt haben, nach Ma\u00dfgabe der gesetzlichen Vorgaben in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten oder deren \u00dcbermittlung an einen anderen Verantwortlichen zu fordern.<\/li>\n<li><strong>Beschwerde bei Aufsichtsbeh\u00f6rde:<\/strong> Sie haben ferner nach Ma\u00dfgabe der gesetzlichen Vorgaben das Recht, bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat Ihres gew\u00f6hnlichen Aufenthaltsorts, Ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes Beschwerde einzulegen, wenn Sie der Ansicht sind, dass die Verarbeitung der Sie betreffenden personenbezogenen Daten gegen die DSGVO verst\u00f6\u00dft.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;12px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<p><strong>Begriffsdefinitionen<\/strong><\/p>\n<p>In diesem Abschnitt erhalten Sie eine \u00dcbersicht \u00fcber die in dieser Datenschutzerkl\u00e4rung verwendeten Begrifflichkeiten. Viele der Begriffe sind dem Gesetz entnommen und vor allem im Art. 4 DSGVO definiert. Die gesetzlichen Definitionen sind verbindlich. Die nachfolgenden Erl\u00e4uterungen sollen dagegen vor allem dem Verst\u00e4ndnis dienen. Die Begriffe sind alphabetisch sortiert.<\/p>\n<ul>\n<li><strong>Personenbezogene Daten:<\/strong> &#8222;Personenbezogene Daten\u201c sind alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person (im Folgenden &#8222;betroffene Person\u201c) beziehen; als identifizierbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung (z.B. Cookie) oder zu einem oder mehreren besonderen Merkmalen identifiziert werden kann, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind.<\/li>\n<li><strong>Reichweitenmessung:<\/strong> Die Reichweitenmessung (auch als Web Analytics bezeichnet) dient der Auswertung der Besucherstr\u00f6me eines Onlineangebotes und kann das Verhalten oder Interessen der Besucher an bestimmten Informationen, wie z.B. Inhalten von Webseiten, umfassen. Mit Hilfe der Reichweitenanalyse k\u00f6nnen Webseiteninhaber z.B. erkennen, zu welcher Zeit Besucher ihre Webseite besuchen und f\u00fcr welche Inhalte sie sich interessieren. Dadurch k\u00f6nnen sie z.B. die Inhalte der Webseite besser an die Bed\u00fcrfnisse ihrer Besucher anpassen. Zu Zwecken der Reichweitenanalyse werden h\u00e4ufig pseudonyme Cookies und Web-Beacons eingesetzt, um wiederkehrende Besucher zu erkennen und so genauere Analysen zur Nutzung eines Onlineangebotes zu erhalten.<\/li>\n<li><strong>Remarketing:<\/strong> Vom &#8222;Remarketing\u201c bzw. &#8222;Retargeting\u201c spricht man, wenn z.B. zu Werbezwecken vermerkt wird, f\u00fcr welche Produkte sich ein Nutzer auf einer Webseite interessiert hat, um den Nutzer auf anderen Webseiten an diese Produkte, z.B. in Werbeanzeigen, zu erinnern.<\/li>\n<li><strong>Tracking:<\/strong> Vom &#8222;Tracking\u201c spricht man, wenn das Verhalten von Nutzern \u00fcber mehrere Onlineangebote hinweg nachvollzogen werden kann. Im Regelfall werden im Hinblick auf die genutzten Onlineangebote Verhaltens- und Interessensinformationen in Cookies oder auf Servern der Anbieter der Trackingtechnologien gespeichert (sogenanntes Profiling). Diese Informationen k\u00f6nnen anschlie\u00dfend z.B. eingesetzt werden, um den Nutzern Werbeanzeigen anzuzeigen, die voraussichtlich deren Interessen entsprechen.<\/li>\n<li><strong>Verantwortlicher:<\/strong> Als &#8222;Verantwortlicher\u201c wird die nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten entscheidet, bezeichnet.<\/li>\n<li><strong>Verarbeitung:<\/strong> &#8222;Verarbeitung&#8220; ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrte Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten. Der Begriff reicht weit und umfasst praktisch jeden Umgang mit Daten, sei es das Erheben, das Auswerten, das Speichern, das \u00dcbermitteln oder das L\u00f6schen.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.3.4&#8243; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;8px&#8220; text_line_height=&#8220;1em&#8220;]<\/p>\n<p>Erstellt mit dem kostenlosem Datenschutz-Generator.de<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.0.9&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_divider color=&#8220;#000000&#8243; _builder_version=&#8220;3.19.1&#8243; height=&#8220;5px&#8220;][\/et_pb_divider][et_pb_text _builder_version=&#8220;4.4.3&#8243; text_font_size=&#8220;12px&#8220; hover_enabled=&#8220;0&#8243;]<\/p>\n<h2>Impressum<\/h2>\n<div class=\"row main-content-wrapper\">\n<div class=\"row\">\n<div class=\"col-md-12 column\">\n<div>Johanna &amp; Alex<\/div>\n<div>Schweiz<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datenschutz und ImpressumDieser Blog verfolgt&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>[et_pb_section fb_built=\"1\" fullwidth=\"on\" _builder_version=\"4.1\"][et_pb_fullwidth_slider _builder_version=\"4.1\" hover_enabled=\"0\"][et_pb_slide heading=\"Legal Information and Impressum\" _builder_version=\"4.1\" hover_enabled=\"0\" background_image=\"https:\/\/cooksringroad.com\/wp-content\/uploads\/2020\/01\/20140518_190147-scaled.jpg\" background_enable_image=\"on\"]<\/p><p style=\"text-align: center;\">This blog does not pursue any commercial purposes<\/p><p>[\/et_pb_slide][\/et_pb_fullwidth_slider][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"3.22\"][et_pb_row _builder_version=\"3.25\" background_size=\"initial\" background_position=\"top_left\" background_repeat=\"repeat\"][et_pb_column type=\"4_4\" _builder_version=\"3.25\" custom_padding=\"|||\" custom_padding__hover=\"|||\"][et_pb_text _builder_version=\"4.0.9\"]<\/p><p>Cook's Ring Road is a purely private and non-commercial blog. We provide information on roadtrips in and recipes from different regions and are very happy to do so on request and for free.<\/p><p>None the less and just to be on the safe side, you will find information on legal aspects below, although this may not even be necessary.<\/p><p>[\/et_pb_text][et_pb_divider color=\"#000000\" _builder_version=\"3.19.1\" height=\"5px\"][\/et_pb_divider][et_pb_text _builder_version=\"4.0.9\" text_font_size=\"13px\"]<\/p><h2>Data Protection<\/h2><div class=\"row main-content-wrapper\"><div class=\"row\"><div class=\"col-md-12 column\"><div><p>We require that you provide us with certain personal data so that we can contact you and provide services to you. We may also use your personal data to monitor and analyse our activities and to comply with any applicable laws or regulations.<\/p><p>We will not disclose personal data to any third person, except with your authorisation. However, we may disclose any personal data if we are required to, requested by or permitted to do so by a court of law, by any governmental or law enforcement agency (including the police), in connection with legal proceedings, or where required by our website internet service provider. We may also disclose any personal data if we determine it is necessary or desirable to comply with any law or to protect or defend our rights or property.<\/p><p>You have the right to receive a copy of the personal data we hold about you. Please contact us via email at\u00a0<a>info@cooksringroad.com<\/a>.<\/p><p>We make every effort to protect the databases from outside access, data loss, misuse or falsification. In case of a breach of our security system, we will contact you at the address you provide us with any relevant information as to the extent of the breach.<\/p><p>Our websites use Google Analytics, an analysis service of Google, Inc. (a corporation with its seat in the United States) in order to evaluate usage and track trends such that we can improve the information on offer. This service uses cookies to collect information (IP address, date, time, browser requests and general information on the operating system and browser) on your use of our websites. Your IP address is rendered anonymous as soon as technically feasible at the earliest possible stage of the collection network. If you no longer wish your access data to be evaluated by Google Analytics, you may download and install the browser add-on for deactivating Google Analytics at:\u00a0<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=en\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=en<\/a>. If you do not want Google to associate data about the use of our website with your Google account, you must log out from this account prior to visiting our website.<\/p><p>You can disable cookies from your computer system by following the instructions on your browser or at\u00a0<a href=\"http:\/\/www.allaboutcookies.org\/\">www.allaboutcookies.org<\/a>.<\/p><p>We may change this Privacy Policy from time to time. Your continued use of the Site will mean that you accept those changes.<\/p><\/div><\/div><\/div><\/div><p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\"3.25\" background_size=\"initial\" background_position=\"top_left\" background_repeat=\"repeat\"][et_pb_column type=\"4_4\" _builder_version=\"3.25\" custom_padding=\"|||\" custom_padding__hover=\"|||\"][et_pb_divider color=\"#000000\" _builder_version=\"3.19.1\" height=\"5px\"][\/et_pb_divider][et_pb_text _builder_version=\"4.0.9\" text_font_size=\"13px\"]<\/p><h2>Datenschutz<\/h2><div class=\"row main-content-wrapper\"><div class=\"row\"><div class=\"col-md-12 column\"><div><p>Diese Datenschutzerkl\u00e4rung soll die Nutzer dieser Website \u00fcber die Art, den Umfang und den Zweck der Erhebung und Verwendung personenbezogener Daten durch den Websitebetreiber (Kontakt unter info@cooksringroad.com) informieren.<\/p><p>Der Websitebetreiber nimmt den Datenschutz sehr ernst und behandelt personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Vorschriften. Da durch neue Technologien und die st\u00e4ndige Weiterentwicklung dieser Webseite \u00c4nderungen an dieser Datenschutzerkl\u00e4rung vorgenommen werden k\u00f6nnen, empfehlen wir, sich die Datenschutzerkl\u00e4rung in regelm\u00e4\u00dfigen Abst\u00e4nden wieder durchzulesen.<\/p><p>Definitionen der verwendeten Begriffe (z.B. \"personenbezogene Daten\" oder \"Verarbeitung\") finden sich in Art. 4 DSGVO.<\/p><\/div><\/div><\/div><\/div><p>[\/et_pb_text][et_pb_text _builder_version=\"4.0.9\" text_font_size=\"13px\"]<\/p><h2>Zugriffsdaten<\/h2><div class=\"row main-content-wrapper\"><div class=\"row\"><div class=\"col-md-12 column\"><div><p>Wir, der Websitebetreiber, erheben aufgrund unseres berechtigten Interesses (s. Art. 6 Abs. 1 lit. f. DSGVO) Daten \u00fcber Zugriffe auf die Website und speichern diese als \"Server-Logfiles\" auf dem Server der Website ab. Folgende Daten werden so protokolliert:<\/p><ul><li>Besuchte Website<\/li><li>Uhrzeit zum Zeitpunkt des Zugriffes<\/li><li>Menge der gesendeten Daten in Byte<\/li><li>Quelle\/Verweis, von welchem Nutzer auf die Seite gelangten<\/li><li>Verwendeter Browser<\/li><li>Verwendetes Betriebssystem<\/li><li>Verwendete IP-Adresse<\/li><\/ul><p>Die Server-Logfiles werden f\u00fcr maximal 7 Tage gespeichert und anschlie\u00dfend gel\u00f6scht. Die Speicherung der Daten erfolgt aus Sicherheitsgr\u00fcnden, um z. B. Missbrauchsf\u00e4lle aufkl\u00e4ren zu k\u00f6nnen. M\u00fcssen Daten aus Beweisgr\u00fcnden aufgehoben werden, sind sie solange von der L\u00f6schung ausgenommen bis der Vorfall endg\u00fcltig gekl\u00e4rt ist.<\/p><\/div><\/div><\/div><\/div><p>[\/et_pb_text][et_pb_text _builder_version=\"4.0.9\" text_font_size=\"13px\"]<\/p><h2>Reichweitenmessung und Cookies<\/h2><div class=\"row main-content-wrapper\"><div class=\"row\"><div class=\"col-md-12 column\"><div><p>Diese Website verwendet Cookies zur pseudonymisierten Reichweitenmessung, die entweder von unserem Server oder dem Server Dritter an den Browser des Nutzers \u00fcbertragen werden. Bei Cookies handelt es sich um kleine Dateien, welche auf Ihrem Endger\u00e4t gespeichert werden. Ihr Browser greift auf diese Dateien zu. Durch den Einsatz von Cookies erh\u00f6ht sich die Benutzerfreundlichkeit und Sicherheit dieser Website.<\/p><p>Falls Sie nicht m\u00f6chten, dass Cookies zur Reichweitenmessung auf Ihrem Endger\u00e4t gespeichert werden, k\u00f6nnen Sie dem Einsatz dieser Dateien hier widersprechen:<\/p><ul><li>Cookie-Deaktivierungsseite der Netzwerkwerbeinitiative: <a href=\"http:\/\/optout.networkadvertising.org\/?c=1#!\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/optout.networkadvertising.org\/?c=1#!\/<\/a><\/li><li>Cookie-Deaktivierungsseite der US-amerikanischen Website: <a href=\"http:\/\/optout.aboutads.info\/?c=2#!\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/optout.aboutads.info\/?c=2#!\/<\/a><\/li><li>Cookie-Deaktivierungsseite der europ\u00e4ischen Website: <a href=\"http:\/\/optout.networkadvertising.org\/?c=1#!\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/optout.networkadvertising.org\/?c=1#!\/<\/a><\/li><\/ul><p>G\u00e4ngige Browser bieten die Einstellungsoption, Cookies nicht zuzulassen. Hinweis: Es ist nicht gew\u00e4hrleistet, dass Sie auf alle Funktionen dieser Website ohne Einschr\u00e4nkungen zugreifen k\u00f6nnen, wenn Sie entsprechende Einstellungen vornehmen.<\/p><\/div><\/div><\/div><\/div><p>[\/et_pb_text][et_pb_text _builder_version=\"4.0.9\" text_font_size=\"13px\"]<\/p><h2>Nutzung von Social Media Plugins<\/h2><div class=\"row main-content-wrapper\"><div class=\"row\"><div class=\"col-md-12 column\"><div><p>Aufgrund unseres berechtigten Interesses an der Analyse, Optimierung und dem Betrieb unseres Online-Angebotes (im Sinne des Art. 6 Abs. 1 lit. f. DSGVO), verwendet diese Website das Facebook-Social-Plugin, welches von der Facebook Inc. (1 Hacker Way, Menlo Park, California 94025, USA) betrieben wird. Erkennbar sind die Einbindungen an dem Facebook-Logo bzw. an den Begriffen \u201eLike\u201c, \u201eGef\u00e4llt mir\u201c, \u201eTeilen\u201c in den Farben Facebooks (Blau und Wei\u00df). Informationen zu allen Facebook-Plugins finden Sie \u00fcber den folgenden Link: <a href=\"https:\/\/developers.facebook.com\/docs\/plugins\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/developers.facebook.com\/docs\/plugins\/<\/a><\/p><p>Facebook Inc. h\u00e4lt das europ\u00e4ische Datenschutzrecht ein und ist unter dem Privacy-Shield-Abkommen zertifiziert: <a href=\"https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000GnywAAC&status=Active\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000GnywAAC&status=Active<\/a><\/p><p>Das Plugin stellt eine direkte Verbindung zwischen Ihrem Browser und den Facebook-Servern her. Der Websitebetreiber hat keinerlei Einfluss auf die Natur und den Umfang der Daten, welche das Plugin an die Server der Facebook Inc. \u00fcbermittelt. Informationen dazu finden Sie hier: <a href=\"https:\/\/www.facebook.com\/help\/186325668085084\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/help\/186325668085084<\/a><\/p><p>Das Plugin informiert die Facebook Inc. dar\u00fcber, dass Sie als Nutzer diese Website besucht haben. Es besteht hierbei die M\u00f6glichkeit, dass Ihre IP-Adresse gespeichert wird. Sind Sie w\u00e4hrend des Besuchs auf dieser Website in Ihrem Facebook-Konto eingeloggt, werden die genannten Informationen mit diesem verkn\u00fcpft.<\/p><p>Nutzen Sie die Funktionen des Plugins \u2013 etwa indem Sie einen Beitrag teilen oder \u201eliken\u201c \u2013, werden die entsprechenden Informationen ebenfalls an die Facebook Inc. \u00fcbermittelt.<br \/>M\u00f6chten Sie verhindern, dass die Facebook. Inc. diese Daten mit Ihrem Facebook-Konto verkn\u00fcpft, loggen Sie sich bitte vor dem Besuch dieser Website bei Facebook aus und l\u00f6schen Sie die gespeicherten Cookies. \u00dcber Ihr Facebook-Profil k\u00f6nnen Sie weitere Einstellungen zur Datenverarbeitung f\u00fcr Werbezwecke t\u00e4tigen oder der Nutzung Ihrer Daten f\u00fcr Werbezwecke widersprechen. Zu den Einstellungen gelangen Sie hier:<\/p><ul><li>Profileinstellungen bei Facebook: <a href=\"https:\/\/www.facebook.com\/ads\/preferences\/?entry_product=ad_settings_screen\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/ads\/preferences\/?entry_product=ad_settings_screen<\/a><\/li><li>Cookie-Deaktivierungsseite der US-amerikanischen Website: <a href=\"http:\/\/optout.aboutads.info\/?c=2#!\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/optout.aboutads.info\/?c=2#!\/<\/a><\/li><li>Cookie-Deaktivierungsseite der europ\u00e4ischen Website: <a href=\"http:\/\/optout.networkadvertising.org\/?c=1#!\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/optout.networkadvertising.org\/?c=1#!\/<\/a><\/li><\/ul><p>Welche Daten, zu welchem Zweck und in welchem Umfang Facebook Daten erhebt, nutzt und verarbeitet und welche Rechte sowie Einstellungsm\u00f6glichkeiten Sie zum Schutz Ihrer Privatsph\u00e4re haben, k\u00f6nnen Sie in den Datenschutzrichtlinien von Facebook nachlesen. Diese finden Sie hier: <a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/about\/privacy\/<\/a><\/p><\/div><\/div><\/div><\/div><p>[\/et_pb_text][et_pb_text _builder_version=\"4.0.9\" text_font_size=\"13px\"]<\/p><h2>Erfassung und Verarbeitung personenbezogener Daten<\/h2><div class=\"row main-content-wrapper\"><div class=\"row\"><div class=\"col-md-12 column\"><div><p>Der Websitebetreiber erhebt, nutzt und gibt Ihre personenbezogenen Daten nur dann weiter, wenn dies im gesetzlichen Rahmen erlaubt ist oder Sie in die Datenerhebung einwilligen.<\/p><p>Als personenbezogene Daten gelten s\u00e4mtliche Informationen, welche dazu dienen, Ihre Person zu bestimmen und welche zu Ihnen zur\u00fcckverfolgt werden k\u00f6nnen \u2013 also beispielsweise Ihr Name, Ihre E-Mail-Adresse und Telefonnummer.<\/p><p>Diese Website k\u00f6nnen Sie auch besuchen, ohne Angaben zu Ihrer Person zu machen. Zur Verbesserung unseres Online-Angebotes speichern wir jedoch (ohne Personenbezug) Ihre Zugriffsdaten auf diese Website. Zu diesen Zugriffsdaten geh\u00f6ren z. B. die von Ihnen angeforderte Datei oder der Name Ihres Internet-Providers. Durch die Anonymisierung der Daten sind R\u00fcckschl\u00fcsse auf Ihre Person nicht m\u00f6glich.<\/p><\/div><\/div><\/div><\/div><p>[\/et_pb_text][et_pb_text _builder_version=\"4.0.9\" text_font_size=\"13px\"]<\/p><h2>Umgang mit Kommentaren und Beitr\u00e4gen<\/h2><div class=\"row main-content-wrapper\"><div class=\"row\"><div class=\"col-md-12 column\"><div>Hinterlassen Sie auf dieser Website einen Beitrag oder Kommentar, wird Ihre IP-Adresse gespeichert. Dies erfolgt aufgrund unserer berechtigten Interessen im Sinne des Art. 6 Abs. 1 lit. f. DSGVO und dient der Sicherheit von uns als Websitebetreiber: Denn sollte Ihr Kommentar gegen geltendes Recht versto\u00dfen, k\u00f6nnen wir daf\u00fcr belangt werden, weshalb wir ein Interesse an der Identit\u00e4t des Kommentar- bzw. Beitragsautors haben.<\/div><\/div><\/div><\/div><p>[\/et_pb_text][et_pb_text _builder_version=\"4.0.9\" text_font_size=\"13px\"]<\/p><h2>Google Analytics<\/h2><div class=\"row main-content-wrapper\"><div class=\"row\"><div class=\"col-md-12 column\"><div><p>Diese Website nutzt aufgrund unserer berechtigten Interessen zur Optimierung und Analyse unseres Online-Angebots im Sinne des Art. 6 Abs. 1 lit. f. DSGVO den Dienst \u201eGoogle Analytics\u201c, welcher von der Google Inc. (1600 Amphitheatre Parkway Mountain View, CA 94043, <a title=\"USA\" href=\"https:\/\/www.datenschutz.org\/usa\/\">USA<\/a>) angeboten wird. Der Dienst (Google Analytics) verwendet \u201eCookies\u201c \u2013 Textdateien, welche auf Ihrem Endger\u00e4t gespeichert werden. Die durch die Cookies gesammelten Informationen werden im Regelfall an einen Google-Server in den USA gesandt und dort gespeichert.<\/p><p>Google LLC h\u00e4lt das europ\u00e4ische Datenschutzrecht ein und ist unter dem Privacy-Shield-Abkommen zertifiziert: <a href=\"https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI&status=Active\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI&status=Active<\/a><\/p><p>Auf dieser Website greift die IP-Anonymisierung. Die IP-Adresse der Nutzer wird innerhalb der Mitgliedsstaaten der EU und des Europ\u00e4ischen Wirtschaftsraum und in den anderen Vertragsstaaten des Abkommens gek\u00fcrzt. Nur in Einzelf\u00e4llen wird die IP-Adresse zun\u00e4chst ungek\u00fcrzt in die USA an einen Server von Google \u00fcbertragen und dort gek\u00fcrzt. Durch diese K\u00fcrzung entf\u00e4llt der Personenbezug Ihrer IP-Adresse. Die vom Browser \u00fcbermittelte IP-Adresse des Nutzers wird nicht mit anderen von Google gespeicherten Daten kombiniert.<\/p><p>Im Rahmen der Vereinbarung zur Auftragsdatenvereinbarung, welche wir als Websitebetreiber mit der Google Inc. geschlossen haben, erstellt diese mithilfe der gesammelten Informationen eine Auswertung der Websitenutzung und der Websiteaktivit\u00e4t und erbringt mit der Internetnutzung verbundene Dienstleistungen.<\/p><p>Die von Google in unserem Auftrag erhobenen Daten werden genutzt, um die Nutzung unseres Online-Angebots durch die einzelnen Nutzer auswerten zu k\u00f6nnen, z. B. um Reports \u00fcber die Aktivit\u00e4t auf der Website zu erstellen, um unser Online-Angebot zu verbessern.<\/p><p>Sie haben die M\u00f6glichkeit, die Speicherung der Cookies auf Ihrem Ger\u00e4t zu verhindern, indem Sie in Ihrem Browser entsprechende Einstellungen vornehmen. Es ist nicht gew\u00e4hrleistet, dass Sie auf alle Funktionen dieser Website ohne Einschr\u00e4nkungen zugreifen k\u00f6nnen, wenn Ihr Browser keine Cookies zul\u00e4sst.<\/p><p>Weiterhin k\u00f6nnen Sie durch ein Browser-Plugin verhindern, dass die durch Cookies gesammelten Informationen (inklusive Ihrer IP-Adresse) an die Google Inc. gesendet und von der Google Inc. genutzt werden. Folgender Link f\u00fchrt Sie zu dem entsprechenden Plugin: <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a><\/p><p>Alternativ verhindern Sie mit einem Klick auf diesen Link (WICHTIG: Opt-Out-Link einf\u00fcgen), dass Google Analytics innerhalb dieser Website Daten \u00fcber Sie erfasst. Mit dem Klick auf obigen Link laden Sie ein \u201eOpt-Out-Cookie\u201c herunter. Ihr Browser muss die Speicherung von Cookies also hierzu grunds\u00e4tzlich erlauben. L\u00f6schen Sie Ihre Cookies regelm\u00e4\u00dfig, ist ein erneuter Klick auf den Link bei jedem Besuch dieser Website vonn\u00f6ten.<\/p><p>Hier finden Sie weitere Informationen zur Datennutzung durch die Google Inc.:<\/p><ul><li><a href=\"https:\/\/policies.google.com\/privacy\/partners?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy\/partners?hl=de<\/a> (Daten, die von Google-Partnern erhoben werden)<\/li><li><a href=\"https:\/\/adssettings.google.de\/authenticated\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/adssettings.google.de\/authenticated<\/a> (Einstellungen \u00fcber <a title=\"Werbung\" href=\"https:\/\/www.datenschutz.org\/werbung\/\">Werbung<\/a>, die Ihnen angezeigt wird)<\/li><li><a href=\"https:\/\/policies.google.com\/technologies\/ads?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/technologies\/ads?hl=de<\/a> (Verwendung von Cookies in Anzeigen)<\/li><\/ul><\/div><\/div><\/div><\/div><p>[\/et_pb_text][et_pb_text _builder_version=\"4.0.9\" text_font_size=\"13px\"]<\/p><h2>Rechte des Nutzers<\/h2><div class=\"row main-content-wrapper\"><div class=\"row\"><div class=\"col-md-12 column\"><div><p>Sie haben als Nutzer das Recht, auf Antrag eine kostenlose Auskunft dar\u00fcber zu erhalten, welche personenbezogenen Daten \u00fcber Sie gespeichert wurden. Sie haben au\u00dferdem das Recht auf Berichtigung falscher Daten und auf die Verarbeitungseinschr\u00e4nkung oder L\u00f6schung Ihrer personenbezogenen Daten. Falls zutreffend, k\u00f6nnen Sie auch Ihr Recht auf Datenportabilit\u00e4t geltend machen. Sollten Sie annehmen, dass Ihre Daten unrechtm\u00e4\u00dfig verarbeitet wurden, k\u00f6nnen Sie eine Beschwerde bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde einreichen.<\/p><\/div><\/div><\/div><\/div><p>[\/et_pb_text][et_pb_text _builder_version=\"4.0.9\" text_font_size=\"13px\"]<\/p><h2>L\u00f6schung von Daten<\/h2><div class=\"row main-content-wrapper\"><div class=\"row\"><div class=\"col-md-12 column\"><div><p>Sofern Ihr Wunsch nicht mit einer gesetzlichen Pflicht zur Aufbewahrung von Daten (z. B. Vorratsdatenspeicherung) kollidiert, haben Sie ein Anrecht auf L\u00f6schung Ihrer Daten. Von uns gespeicherte Daten werden, sollten sie f\u00fcr ihre Zweckbestimmung nicht mehr vonn\u00f6ten sein und es keine gesetzlichen Aufbewahrungsfristen geben, gel\u00f6scht. Falls eine L\u00f6schung nicht durchgef\u00fchrt werden kann, da die Daten f\u00fcr zul\u00e4ssige gesetzliche Zwecke erforderlich sind, erfolgt eine Einschr\u00e4nkung der Datenverarbeitung. In diesem Fall werden die Daten gesperrt und nicht f\u00fcr andere Zwecke verarbeitet.<\/p><\/div><\/div><\/div><\/div><p>[\/et_pb_text][et_pb_text _builder_version=\"4.0.9\" text_font_size=\"13px\"]<\/p><h2>Widerspruchsrecht<\/h2><div class=\"row main-content-wrapper\"><div class=\"row\"><div class=\"col-md-12 column\"><div><p>Nutzer dieser Webseite k\u00f6nnen von ihrem Widerspruchsrecht Gebrauch machen und der Verarbeitung ihrer personenbezogenen Daten zu jeder Zeit widersprechen.<\/p><p>Wenn Sie eine Berichtigung, Sperrung, L\u00f6schung oder Auskunft \u00fcber die zu Ihrer Person gespeicherten personenbezogenen Daten w\u00fcnschen oder Fragen bzgl. der Erhebung, Verarbeitung oder Verwendung Ihrer personenbezogenen Daten haben oder erteilte Einwilligungen widerrufen m\u00f6chten, wenden Sie sich bitte an folgende E-Mail-Adresse: info@cooksringroad.com.<\/p><\/div><\/div><\/div><\/div><p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\"4.0.9\" background_size=\"initial\" background_position=\"top_left\" background_repeat=\"repeat\"][et_pb_column type=\"4_4\" _builder_version=\"3.25\" custom_padding=\"|||\" custom_padding__hover=\"|||\"][et_pb_divider color=\"#000000\" _builder_version=\"3.19.1\" height=\"5px\"][\/et_pb_divider][et_pb_text _builder_version=\"4.0.9\" text_font_size=\"13px\"]<\/p><h2>Impressum<\/h2><div class=\"row main-content-wrapper\"><div class=\"row\"><div class=\"col-md-12 column\"><div>J. Fournier & A. Perera<\/div><div>Switzerland<\/div><\/div><\/div><\/div><p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","_et_gb_content_width":"","footnotes":""},"class_list":["post-29615","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cook&#039;s Ring Road - DATENSCHUTZ UND IMPRESSUM<\/title>\n<meta name=\"description\" content=\"Cook&#039;s Ring Road ist ein Blog, der Vorschl\u00e4ge f\u00fcr Roadtrips und Rezepte kombiniert, immer mit Bezug zu bestimmten Regionen. Frag uns und wir geben dir Anregungen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cooksringroad.com\/de\/datenschutz-und-impressum\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cook&#039;s Ring Road - DATENSCHUTZ UND IMPRESSUM\" \/>\n<meta property=\"og:description\" content=\"Cook&#039;s Ring Road ist ein Blog, der Vorschl\u00e4ge f\u00fcr Roadtrips und Rezepte kombiniert, immer mit Bezug zu bestimmten Regionen. Frag uns und wir geben dir Anregungen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cooksringroad.com\/de\/datenschutz-und-impressum\/\" \/>\n<meta property=\"og:site_name\" content=\"Cook&#039;s Ring Road\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Cooks-Ring-Road-114397376673668\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-17T10:52:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cooksringroad\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"23\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cooksringroad.com\\\/de\\\/datenschutz-und-impressum\\\/\",\"url\":\"https:\\\/\\\/cooksringroad.com\\\/de\\\/datenschutz-und-impressum\\\/\",\"name\":\"Cook&#039;s Ring Road - DATENSCHUTZ UND IMPRESSUM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cooksringroad.com\\\/de\\\/#website\"},\"datePublished\":\"2020-01-26T11:01:06+00:00\",\"dateModified\":\"2020-04-17T10:52:38+00:00\",\"description\":\"Cook's Ring Road ist ein Blog, der Vorschl\u00e4ge f\u00fcr Roadtrips und Rezepte kombiniert, immer mit Bezug zu bestimmten Regionen. Frag uns und wir geben dir Anregungen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cooksringroad.com\\\/de\\\/datenschutz-und-impressum\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cooksringroad.com\\\/de\\\/datenschutz-und-impressum\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cooksringroad.com\\\/de\\\/datenschutz-und-impressum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cooksringroad.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DATENSCHUTZ UND IMPRESSUM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cooksringroad.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/cooksringroad.com\\\/de\\\/\",\"name\":\"Cook's Ring Road\",\"description\":\"Roadtrips and Recipes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cooksringroad.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cook&#039;s Ring Road - DATENSCHUTZ UND IMPRESSUM","description":"Cook's Ring Road ist ein Blog, der Vorschl\u00e4ge f\u00fcr Roadtrips und Rezepte kombiniert, immer mit Bezug zu bestimmten Regionen. Frag uns und wir geben dir Anregungen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cooksringroad.com\/de\/datenschutz-und-impressum\/","og_locale":"de_DE","og_type":"article","og_title":"Cook&#039;s Ring Road - DATENSCHUTZ UND IMPRESSUM","og_description":"Cook's Ring Road ist ein Blog, der Vorschl\u00e4ge f\u00fcr Roadtrips und Rezepte kombiniert, immer mit Bezug zu bestimmten Regionen. Frag uns und wir geben dir Anregungen!","og_url":"https:\/\/cooksringroad.com\/de\/datenschutz-und-impressum\/","og_site_name":"Cook&#039;s Ring Road","article_publisher":"https:\/\/www.facebook.com\/Cooks-Ring-Road-114397376673668\/","article_modified_time":"2020-04-17T10:52:38+00:00","twitter_card":"summary_large_image","twitter_site":"@cooksringroad","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"23\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cooksringroad.com\/de\/datenschutz-und-impressum\/","url":"https:\/\/cooksringroad.com\/de\/datenschutz-und-impressum\/","name":"Cook&#039;s Ring Road - DATENSCHUTZ UND IMPRESSUM","isPartOf":{"@id":"https:\/\/cooksringroad.com\/de\/#website"},"datePublished":"2020-01-26T11:01:06+00:00","dateModified":"2020-04-17T10:52:38+00:00","description":"Cook's Ring Road ist ein Blog, der Vorschl\u00e4ge f\u00fcr Roadtrips und Rezepte kombiniert, immer mit Bezug zu bestimmten Regionen. Frag uns und wir geben dir Anregungen!","breadcrumb":{"@id":"https:\/\/cooksringroad.com\/de\/datenschutz-und-impressum\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cooksringroad.com\/de\/datenschutz-und-impressum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cooksringroad.com\/de\/datenschutz-und-impressum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cooksringroad.com\/de\/"},{"@type":"ListItem","position":2,"name":"DATENSCHUTZ UND IMPRESSUM"}]},{"@type":"WebSite","@id":"https:\/\/cooksringroad.com\/de\/#website","url":"https:\/\/cooksringroad.com\/de\/","name":"Cook's Ring Road","description":"Roadtrips and Recipes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cooksringroad.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/cooksringroad.com\/de\/wp-json\/wp\/v2\/pages\/29615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cooksringroad.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cooksringroad.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cooksringroad.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cooksringroad.com\/de\/wp-json\/wp\/v2\/comments?post=29615"}],"version-history":[{"count":26,"href":"https:\/\/cooksringroad.com\/de\/wp-json\/wp\/v2\/pages\/29615\/revisions"}],"predecessor-version":[{"id":30861,"href":"https:\/\/cooksringroad.com\/de\/wp-json\/wp\/v2\/pages\/29615\/revisions\/30861"}],"wp:attachment":[{"href":"https:\/\/cooksringroad.com\/de\/wp-json\/wp\/v2\/media?parent=29615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}